{"id":313,"date":"2013-11-22T09:26:19","date_gmt":"2013-11-22T00:26:19","guid":{"rendered":"https:\/\/profession-net.com\/bookstore\/?p=3248"},"modified":"2026-08-12T12:53:41","modified_gmt":"2026-08-12T03:53:41","slug":"s70445","status":"publish","type":"product","link":"https:\/\/profession-net.com\/bookstore\/s70445\/","title":{"rendered":"\u76f8\u7d9a\u7a0e\u30fb\u8d08\u4e0e\u7a0e\u306e \u682a\u5f0f\u8a55\u4fa1\u5b9f\u52d9\u5fc5\u643a"},"content":{"rendered":"<div class=\"text mb-0\">\n<\/div>","protected":false},"excerpt":{"rendered":"<p>\u76f8\u7d9a\u7a0e\u53ca\u3073\u8d08\u4e0e\u7a0e\u306e\u7533\u544a\u306b\u3042\u305f\u3063\u3066\u306e\u682a\u5f0f\u306e\u8a55\u4fa1\u65b9\u6cd5\u3092\u5b9a\u3081\u305f\u300c\u8ca1\u7523\u8a55\u4fa1\u57fa\u672c\u901a\u9054\u300d\u306b\u304a\u3044\u3066\u3001\u7279\u306b\u96e3\u89e3\u306a\u53d6\u5f15\u76f8\u5834\u306e\u306a\u3044\u682a\u5f0f\u306e\u8a55\u4fa1\u65b9\u6cd5\u3092\u4e2d\u5fc3\u306b\u3001\u5177\u4f53\u7684\u306a\u56f3\u89e3\u3068\u4e8b\u4f8b\u306e\u69cb\u6210\u3067\u8a73\u7d30\u89e3\u8aac\u3002<\/p>\n","protected":false},"featured_media":37400,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_cat":[15,7,8],"product_tag":[49],"acf":[],"_links":{"self":[{"href":"https:\/\/profession-net.com\/bookstore\/wp-json\/wp\/v2\/product\/313"}],"collection":[{"href":"https:\/\/profession-net.com\/bookstore\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/profession-net.com\/bookstore\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/profession-net.com\/bookstore\/wp-json\/wp\/v2\/comments?post=313"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/profession-net.com\/bookstore\/wp-json\/wp\/v2\/media\/37400"}],"wp:attachment":[{"href":"https:\/\/profession-net.com\/bookstore\/wp-json\/wp\/v2\/media?parent=313"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/profession-net.com\/bookstore\/wp-json\/wp\/v2\/product_cat?post=313"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/profession-net.com\/bookstore\/wp-json\/wp\/v2\/product_tag?post=313"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}